{"id":114328,"date":"2023-07-13T12:06:31","date_gmt":"2023-07-13T10:06:31","guid":{"rendered":"https:\/\/iconproducts.com\/?page_id=114328"},"modified":"2025-06-12T09:39:49","modified_gmt":"2025-06-12T07:39:49","slug":"india-cleansing-shampoo","status":"publish","type":"page","link":"https:\/\/iconproducts.com\/es\/icon-india\/india-cleansing-shampoo\/","title":{"rendered":"India Cleansing Shampoo"},"content":{"rendered":"<p>[vc_row][vc_column]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"100\" data-normal_resolution=\"1024\" data-normal_size=\"100\" data-tablet_resolution=\"800\" data-tablet_size=\"50\" data-mobile_resolution=\"480\" data-mobile_size=\"50\" style=\"height: 100px;\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;]<div id=\"dfd-single-image-module6a97c91575860-2169\" class=\"dfd-single-image-module  image-center \" ><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/iconproducts.com\/wp-content\/uploads\/2023\/07\/indiaweb2023-cleansing-shampoo-2.jpg\" width=\"1000\" height=\"1000\"  alt=\"Image module\" \/><\/div><div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"50\" data-normal_resolution=\"1024\" data-normal_size=\"50\" data-tablet_resolution=\"800\" data-tablet_size=\"50\" data-mobile_resolution=\"480\" data-mobile_size=\"50\" style=\"height: 50px;\"><\/div>[\/vc_column][vc_column width=\u00bb1\/2&#8243;]<div class=\"dfd-heading-shortcode\"><div class=\"dfd-heading-module-wrap  text-left style_01 dfd-heading-6a97c915758fc dfd-disable-resposive-headings\" id=\"dfd-heading-6a97c915758fc\" ><div class=\"inline-block\"><div class=\"dfd-heading-module\"><h1 class=\"widget-title dfd-title \" style=\"\">Champ\u00fa<\/h1><h1 class=\"widget-sub-title dfd-sub-title \" style=\"\">Champ\u00fa limpiador<\/h1><div class=\"dfd-heading-delimiter\"><\/div><\/div><\/div><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\t\t\t\t$(\"head\").append(\"<style>.dfd-heading-6a97c915758fc.dfd-heading-module-wrap .dfd-heading-module .dfd-heading-delimiter {border-bottom-style:solid;border-bottom-width:1px;width:100px;border-bottom-color:#dddddd;}.dfd-heading-6a97c915758fc.dfd-heading-module-wrap .dfd-heading-module .dfd-heading-delimiter {margin-top:10px;margin-bottom:10px;}<\/style>\");\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div>[vc_column_text]<strong>Qu\u00e9 es<\/strong>:<br \/>\nChamp\u00fa limpiador y nutritivo.<\/p>\n<p><strong>Para qui\u00e9n es<\/strong>:<br \/>\nPara todo tipo de cabellos.<\/p>\n<p><strong>Qu\u00e9 hace<\/strong>:<br \/>\nDeja un cabello limpio, nutrido y con cuerpo.<\/p>\n<p><strong>C\u00f3mo se utiliza<\/strong>:<br \/>\nEmulsionar y aplicar sobre cabello mojado, aclarar abundantemente.[\/vc_column_text]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"20\" data-normal_resolution=\"1024\" data-normal_size=\"20\" data-tablet_resolution=\"800\" data-tablet_size=\"20\" data-mobile_resolution=\"480\" data-mobile_size=\"20\" style=\"height: 20px;\"><\/div><div id=\"dfd-button-6a97c91575ac5\" class=\"dfd-button-module-wrap dfd-button-6a97c91575ac5\"><div class=\"dfd-button-module  style_3 text-left dfd-horizontal dfd-top-to-bottom dfd-button-icon-left dfd-button-icon-hover-simple\" ><a href=\"https:\/\/iconproducts.com\/es\/qr\/india-cleansing-shampoo\/\" title=\"India Cleansing Shampoo\" class=\"dfd-button-link\"><span class=\"dfd-button-inner-cover\"><span class=\"dfd-button-text-main\"><i class=\"dfd-icon-copy_doc2\"><\/i>M\u00e1s informaci\u00f3n<\/span><\/span><\/a><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {$(\"head\").append(\"<style>#dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover span i, .dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover span i {font-size: 18px;}#dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main {color: #ffffff}#dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover,.dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-border-decoration,.dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover {border-radius:2px;}#dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:before,#dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:after,#dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module.style_6 .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:before,.dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:after,.dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module.style_6 .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main {background: #1b1b1b;border-style:solid;border-width:1px;border-radius:2px;border-color:#1b1b1b;}#dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module:not(.style_6) .dfd-button-link:hover .dfd-button-inner-cover .dfd-button-text-main,#dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover,.dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module:not(.style_6) .dfd-button-link:hover .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover {color: #000000;}#dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-inner-cover,.dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-border-decoration,.dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-inner-cover {border-radius:2px;}#dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:after,#dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:before,#dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover .dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:after,.dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:before,.dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover {background: #ffffff;border-style:solid;border-width:1px;border-radius:2px;border-color:#045db5;}#dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module.style_3 .dfd-button-link:hover .dfd-button-inner-cover:before,#dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link:hover .dfd-button-inner-cover:before,.dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module.style_3 .dfd-button-link:hover .dfd-button-inner-cover:before,.dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link:hover .dfd-button-inner-cover:before {border-style:solid;border-width:1px;border-radius:2px;border-color:#045db5;}#dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-inner-cover .dfd-button-text-main i,.dfd-button-6a97c91575ac5.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-inner-cover .dfd-button-text-main i {color: #045db5;}<\/style>\")\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div><div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"20\" data-normal_resolution=\"1024\" data-normal_size=\"20\" data-tablet_resolution=\"800\" data-tablet_size=\"20\" data-mobile_resolution=\"480\" data-mobile_size=\"20\" style=\"height: 20px;\"><\/div><div class=\"dfd-delimier-main-wrapper \" ><div id=\"dfd-delimiter-6a97c91575baf-7565\"  class=\"dfd-delimier-wrapper dfd-delimiter-with-line \"  style='text-align:left; ' ><span><span class=\"line\" style=\"border-bottom-width:1px; border-bottom-style:dotted; \"><\/span><\/span><\/div><\/div><div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"20\" data-normal_resolution=\"1024\" data-normal_size=\"20\" data-tablet_resolution=\"800\" data-tablet_size=\"20\" data-mobile_resolution=\"480\" data-mobile_size=\"20\" style=\"height: 20px;\"><\/div>[vc_row_inner el_class=\u00bbbloque-tamanos\u00bb][vc_column_inner][vc_column_text]<strong>Tama\u00f1os disponibles<\/strong>:[\/vc_column_text]<div class=\"dfd-info-banner style-01  text-center\" ><div class=\"image-cover \"><img decoding=\"async\" src=\"https:\/\/iconproducts.com\/wp-content\/uploads\/2023\/11\/india-237ml-60x100.jpg\" alt=\"Image\"  width=\"60\" height=\"100\" class=\"info-banner-image \" \/><\/div><div class=\"info-box-title feature-title\" style=\"\">237 ml.<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" ><\/div><\/div><\/div><div class=\"dfd-info-banner style-01  text-center\" ><div class=\"image-cover \"><img decoding=\"async\" src=\"https:\/\/iconproducts.com\/wp-content\/uploads\/2023\/09\/litro-india-60x100.jpg\" alt=\"Image\"  width=\"60\" height=\"100\" class=\"info-banner-image \" \/><\/div><div class=\"info-box-title feature-title\" style=\"\">1 l.<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" ><\/div><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=\u00bbbtn-buy\u00bb][vc_column_inner]<div class=\"dfd-delimier-main-wrapper \" ><div id=\"dfd-delimiter-6a97c91576233-4926\"  class=\"dfd-delimier-wrapper dfd-delimiter-with-line \"  style='text-align:left; ' ><span><span class=\"line\" style=\"border-bottom-width:1px; border-bottom-style:dotted; \"><\/span><\/span><\/div><\/div><div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"20\" data-normal_resolution=\"1024\" data-normal_size=\"20\" data-tablet_resolution=\"800\" data-tablet_size=\"20\" data-mobile_resolution=\"480\" data-mobile_size=\"20\" style=\"height: 20px;\"><\/div><div id=\"dfd-button-6a97c915762e4\" class=\"dfd-button-module-wrap dfd-button-6a97c915762e4\"><div class=\"dfd-button-module  style_3 text-left dfd-horizontal dfd-top-to-bottom dfd-button-icon-left dfd-button-icon-hover-simple\" ><a href=\"https:\/\/iconproducts.com\/es\/comprar-icon\/?utm_medium=buscador%20&#038;utm_source=productos+web\" title=\"Buscador\" target=\"_blank\" class=\"dfd-button-link\"><span class=\"dfd-button-inner-cover\"><span class=\"dfd-button-text-main\"><i class=\"dfd-icon-right_6\"><\/i>Compra este producto<\/span><\/span><\/a><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {$(\"head\").append(\"<style>#dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover span i, .dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover span i {font-size: 18px;}#dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main {color: #ffffff}#dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover,.dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-border-decoration,.dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover {border-radius:2px;}#dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:before,#dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:after,#dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module.style_6 .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:before,.dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:after,.dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module.style_6 .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main {background: #1b1b1b;border-style:solid;border-width:1px;border-radius:2px;border-color:#1b1b1b;}#dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module:not(.style_6) .dfd-button-link:hover .dfd-button-inner-cover .dfd-button-text-main,#dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover,.dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module:not(.style_6) .dfd-button-link:hover .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover {color: #000000;}#dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-inner-cover,.dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-border-decoration,.dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-inner-cover {border-radius:2px;}#dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:after,#dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:before,#dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover .dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:after,.dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:before,.dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover {background: #ffffff;border-style:solid;border-width:1px;border-radius:2px;border-color:#045db5;}#dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module.style_3 .dfd-button-link:hover .dfd-button-inner-cover:before,#dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link:hover .dfd-button-inner-cover:before,.dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module.style_3 .dfd-button-link:hover .dfd-button-inner-cover:before,.dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link:hover .dfd-button-inner-cover:before {border-style:solid;border-width:1px;border-radius:2px;border-color:#045db5;}#dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-inner-cover .dfd-button-text-main i,.dfd-button-6a97c915762e4.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-inner-cover .dfd-button-text-main i {color: #045db5;}<\/style>\")\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_section el_id=\u00bbnew-ficha-product\u00bb css=\u00bb.vc_custom_1650218698125{margin-bottom: 60px !important;}\u00bb][vc_row][vc_column]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"50\" data-normal_resolution=\"1024\" data-normal_size=\"50\" data-tablet_resolution=\"800\" data-tablet_size=\"50\" data-mobile_resolution=\"480\" data-mobile_size=\"50\" style=\"height: 50px;\"><\/div>[dfd_tta_tabs style=\u00bbempty_style\u00bb tab_title_uppercase=\u00bbuppercase\u00bb font_size=\u00bb15&#8243; icon_size=\u00bb15&#8243; active_section=\u00bb1&#8243; tab_title_font_options=\u00bbfont_style_bold:1&#8243;][vc_tta_section i_position=\u00bbright\u00bb i_icon_fontawesome=\u00bbfas fa-plus\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbIngredientes Activos\u00bb tab_id=\u00bb1648023039495-7bc2b53a-3435&#8243;]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"10\" data-normal_resolution=\"1024\" data-normal_size=\"10\" data-tablet_resolution=\"800\" data-tablet_size=\"10\" data-mobile_resolution=\"480\" data-mobile_size=\"10\" style=\"height: 10px;\"><\/div>[vc_row_inner][vc_column_inner width=\u00bb1\/3&#8243; css=\u00bb.vc_custom_1648024148386{padding-bottom: 40px !important;}\u00bb col_inner_shadow=\u00bbbox_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)\u00bb col_inner_shadow_hover=\u00bbbox_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)\u00bb]<div id=\"idinfobox6a97c91576427\" class=\"dfd-info-box clearfix style-01 layout-04 box-ficha-product idinfobox6a97c91576427\" ><div class=\"dfd-animate-container\"><div class=\"icon-wrapper\"><div class=\"module-icon\" ><div class=\"hover-layer\" ><\/div><img decoding=\"async\" src=\"https:\/\/iconproducts.com\/wp-content\/uploads\/2018\/06\/moringa.png\" alt=\"Image icon\" style=\"opacity: 1;\" \/><\/div><\/div><div class=\"content-wrap ovh\"><div class=\"info-box-title feature-title\" style=\"font-size: 18px; font-weight:bold; \">ACEITE DE MORINGA<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" ><\/div><\/div><div class=\"description\" style=\"\">Contiene m\u00e1s de 90 nutrientes, lo que lo convierte en indispensable para reparar y curar nuestro cabello.<\/div><\/div><\/div><\/div>[\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243; css=\u00bb.vc_custom_1648024152883{padding-bottom: 40px !important;}\u00bb col_inner_shadow=\u00bbbox_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)\u00bb col_inner_shadow_hover=\u00bbbox_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)\u00bb]<div id=\"idinfobox6a97c9157662f\" class=\"dfd-info-box clearfix style-01 layout-04 box-ficha-product idinfobox6a97c9157662f\" ><div class=\"dfd-animate-container\"><div class=\"icon-wrapper\"><div class=\"module-icon\" ><div class=\"hover-layer\" ><\/div><img decoding=\"async\" src=\"https:\/\/iconproducts.com\/wp-content\/uploads\/2018\/06\/argan.png\" alt=\"Image icon\" style=\"opacity: 1;\" \/><\/div><\/div><div class=\"content-wrap ovh\"><div class=\"info-box-title feature-title\" style=\"font-size: 18px; font-weight:bold; \">ACEITE DE ARG\u00c1N<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" ><\/div><\/div><div class=\"description\" style=\"\">Nutre e hidrata facilitando el peinado y evitando el cabello encrespado<\/div><\/div><\/div><\/div>[\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243; css=\u00bb.vc_custom_1648024158832{padding-bottom: 40px !important;}\u00bb col_inner_shadow=\u00bbbox_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)\u00bb col_inner_shadow_hover=\u00bbbox_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)\u00bb]<div id=\"idinfobox6a97c915767db\" class=\"dfd-info-box clearfix style-01 layout-04 box-ficha-product idinfobox6a97c915767db\" ><div class=\"dfd-animate-container\"><div class=\"icon-wrapper\"><div class=\"module-icon\" ><div class=\"hover-layer\" ><\/div><img decoding=\"async\" src=\"https:\/\/iconproducts.com\/wp-content\/uploads\/2018\/06\/ambar.png\" alt=\"Image icon\" style=\"opacity: 1;\" \/><\/div><\/div><div class=\"content-wrap ovh\"><div class=\"info-box-title feature-title\" style=\"font-size: 17px; font-weight:bold; \">AMBAR<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" ><\/div><\/div><div class=\"description\" style=\"\">Esta fragancia utilizada desde la antig\u00fcedad nos envuelve, calmando nuestros sentidos y aumentando nuestra energ\u00eda<\/div><\/div><\/div><\/div>[\/vc_column_inner][\/vc_row_inner]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"20\" data-normal_resolution=\"1024\" data-normal_size=\"20\" data-tablet_resolution=\"800\" data-tablet_size=\"50\" data-mobile_resolution=\"480\" data-mobile_size=\"50\" style=\"height: 20px;\"><\/div>[vc_row_inner][vc_column_inner width=\u00bb1\/2&#8243;]<div id=\"idinfobox6a97c915769fa\" class=\"dfd-info-box clearfix style-01 layout-04 box-ficha-product idinfobox6a97c915769fa\" ><div class=\"dfd-animate-container\"><div class=\"icon-wrapper\"><div class=\"module-icon\" ><div class=\"hover-layer\" ><\/div><img decoding=\"async\" src=\"https:\/\/iconproducts.com\/wp-content\/uploads\/2023\/07\/mauritia-fruit.jpg\" alt=\"Image icon\" style=\"opacity: 1;\" \/><\/div><\/div><div class=\"content-wrap ovh\"><div class=\"info-box-title feature-title\" style=\"font-size: 17px; font-weight:bold; \">FRUTA MAURITIA<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" ><\/div><\/div><div class=\"description\" style=\"\">Una fruta del Amazonas que aporta hidrataci\u00f3n y brillo al cabello. <\/div><\/div><\/div><\/div>[\/vc_column_inner][vc_column_inner width=\u00bb1\/2&#8243;]<div id=\"idinfobox6a97c91576ba7\" class=\"dfd-info-box clearfix style-01 layout-04 box-ficha-product idinfobox6a97c91576ba7\" ><div class=\"dfd-animate-container\"><div class=\"icon-wrapper\"><div class=\"module-icon\" ><div class=\"hover-layer\" ><\/div><img decoding=\"async\" src=\"https:\/\/iconproducts.com\/wp-content\/uploads\/2023\/07\/bacoca-leaves.jpg\" alt=\"Image icon\" style=\"opacity: 1;\" \/><\/div><\/div><div class=\"content-wrap ovh\"><div class=\"info-box-title feature-title\" style=\"font-size: 17px; font-weight:bold; \">BACOPA<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" ><\/div><\/div><div class=\"description\" style=\"\">Planta utilizada en Ayurveda desde la antig\u00fcedad por sus propiedades antioxidantes. Proporciona fuerza y previene la ca\u00edda del cabello.<\/div><\/div><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section i_position=\u00bbright\u00bb i_icon_fontawesome=\u00bbfas fa-plus\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbIngredientes\u00bb tab_id=\u00bb1647965598517-cf28458a-0f46&#8243;][vc_column_text]<em>AQUA (WATER\/EAU), Sodium C14-16 Olefin Sulfonate, Cocamidopropyl Betaine, Sodium Methyl Cocoyl Taurate, Acrylates Copolymer, Argania Spinosa Kernel Oil, Bacopa Monnieri Extract, Caprylyl Glycol, Centella Asiatica Extract, Cetrimonium Chloride, Chlorphenesin, Citric Acid, Cocamide MIPA, Cocoglucosides Hydroxypropyltrimonium Chloride, Ethylhexylyglycerin, Glycerin, Guar Hydroxypropyltrimonium Chloride, Hydrolyzed Pea Protein, Leuconostoc\/Radish Root Ferment Filtrate, Mauritia Flexuosa Fruit Oil, Moringa Oleifera Seed Oil, Panthenol, PEG-150 Distearate, PEG-200 Hydrogenated Glyceryl Palmate, PEG-7 Glyceryl Cocoate, Pentylene Glycol, Pisum Sativum (Pea) Peptide, Polyquaternium-7, Potassium Sorbate, Propanediol, Sesamum Indicum (Sesame) Seed Oil, Sodium Lauroyl Glycinate, Sodium Hydroxide, Sodium Levulinate, PARFUM (Fragrance), Caramel, Eugenol, Hexyl Cinnamal.<\/em><\/p>\n<p>Nos comprometemos a ofrecer productos de alta calidad, naturales y respetuosos con el medio ambiente, de alto rendimiento e innovadores. Nuestra lista de ingredientes puede variar de vez en cuando, ya que nos mantenemos por encima de todas las normativas. Por favor, consulte el envase impreso para obtener la lista de ingredientes m\u00e1s precisa.[\/vc_column_text][\/vc_tta_section][vc_tta_section i_position=\u00bbright\u00bb i_icon_fontawesome=\u00bbfas fa-plus\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbPRODUCTOS RELACIONADOS\u00bb tab_id=\u00bb1647966124315-b6c96e74-d954&#8243;][vc_row_inner][vc_column_inner width=\u00bb1\/3&#8243;]<div id=\"idinfobox6a97c91576d93\" class=\"dfd-info-box clearfix style-01 layout-01 icono-img idinfobox6a97c91576d93 text-center\" ><div class=\"dfd-animate-container\"><div class=\"icon-wrapper\"><div class=\"module-icon\" ><div class=\"hover-layer\" ><\/div><img decoding=\"async\" src=\"https:\/\/iconproducts.com\/wp-content\/uploads\/2023\/07\/indiaweb2023-nourishing-shampoo.jpg\" alt=\"Image icon\" style=\"opacity: 1;\" \/><\/div><\/div><h6 class=\"info-box-title \" style=\"\">India<\/h6><div class=\"info-box-subtitle subtitle\" style=\"\">Nourishing Shampoo<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" style=\"border-color:#ffffff;\"><\/div><\/div><div class=\"description\" style=\"\"><\/div><a href=\"https:\/\/iconproducts.com\/es\/icon-india\/india-nourishing-shampoo\/\" title=\"India Conditioner\"  class=\"full-box-link\"><\/a><\/div><\/div>[\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;]<div id=\"idinfobox6a97c91576f57\" class=\"dfd-info-box clearfix style-01 layout-01 icono-img idinfobox6a97c91576f57 text-center\" ><div class=\"dfd-animate-container\"><div class=\"icon-wrapper\"><div class=\"module-icon\" ><div class=\"hover-layer\" ><\/div><img decoding=\"async\" src=\"https:\/\/iconproducts.com\/wp-content\/uploads\/2023\/07\/indiaweb2023-conditioning-treatment.jpg\" alt=\"Image icon\" style=\"opacity: 1;\" \/><\/div><\/div><h6 class=\"info-box-title \" style=\"\">India<\/h6><div class=\"info-box-subtitle subtitle\" style=\"\">Conditioning Treatment<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" style=\"border-color:#ffffff;\"><\/div><\/div><div class=\"description\" style=\"\"><\/div><a href=\"https:\/\/iconproducts.com\/es\/icon-india\/india-conditioning-treatment\/\"   class=\"full-box-link\"><\/a><\/div><\/div>[\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;]<div id=\"idinfobox6a97c9157715c\" class=\"dfd-info-box clearfix style-01 layout-01 icono-img idinfobox6a97c9157715c text-center\" ><div class=\"dfd-animate-container\"><div class=\"icon-wrapper\"><div class=\"module-icon\" ><div class=\"hover-layer\" ><\/div><img decoding=\"async\" src=\"https:\/\/iconproducts.com\/wp-content\/uploads\/2023\/07\/indiaweb2023-supercharged-mask.jpg\" alt=\"Image icon\" style=\"opacity: 1;\" \/><\/div><\/div><h6 class=\"info-box-title \" style=\"\">India<\/h6><div class=\"info-box-subtitle subtitle\" style=\"\">Supercharged mask<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" style=\"border-color:#ffffff;\"><\/div><\/div><div class=\"description\" style=\"\"><\/div><a href=\"https:\/\/iconproducts.com\/es\/icon-india\/india-supercharged-mask\/\"   class=\"full-box-link\"><\/a><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][\/dfd_tta_tabs][\/vc_column][\/vc_row][\/vc_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_column_text]Qu\u00e9 es: Champ\u00fa limpiador y nutritivo. Para qui\u00e9n es: Para todo tipo de cabellos. Qu\u00e9 hace: Deja un cabello limpio, nutrido y con cuerpo. C\u00f3mo se utiliza: Emulsionar<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":19977,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"wf_page_folders":[369],"class_list":["post-114328","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>India Cleansing Shampoo | I.C.O.N. Products<\/title>\n<meta name=\"description\" content=\"India Cleansing de ICON, champ\u00fa limpiador y nutritivo para todo tipo de cabellos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iconproducts.com\/es\/icon-india\/india-cleansing-shampoo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"India Cleansing Shampoo | I.C.O.N. Products\" \/>\n<meta property=\"og:description\" content=\"India Cleansing de ICON, champ\u00fa limpiador y nutritivo para todo tipo de cabellos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iconproducts.com\/es\/icon-india\/india-cleansing-shampoo\/\" \/>\n<meta property=\"og:site_name\" content=\"I.C.O.N. Products\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/iconproducts.spain\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-12T07:39:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iconproducts.com\\\/es\\\/icon-india\\\/india-cleansing-shampoo\\\/\",\"url\":\"https:\\\/\\\/iconproducts.com\\\/es\\\/icon-india\\\/india-cleansing-shampoo\\\/\",\"name\":\"India Cleansing Shampoo | I.C.O.N. Products\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iconproducts.com\\\/es\\\/#website\"},\"datePublished\":\"2023-07-13T10:06:31+00:00\",\"dateModified\":\"2025-06-12T07:39:49+00:00\",\"description\":\"India Cleansing de ICON, champ\u00fa limpiador y nutritivo para todo tipo de cabellos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iconproducts.com\\\/es\\\/icon-india\\\/india-cleansing-shampoo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iconproducts.com\\\/es\\\/icon-india\\\/india-cleansing-shampoo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iconproducts.com\\\/es\\\/icon-india\\\/india-cleansing-shampoo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"I.C.O.N. Products\",\"item\":\"https:\\\/\\\/iconproducts.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"India\",\"item\":\"https:\\\/\\\/iconproducts.com\\\/es\\\/icon-india\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"India Cleansing Shampoo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iconproducts.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/iconproducts.com\\\/es\\\/\",\"name\":\"I.C.O.N. Products\",\"description\":\"Productos de peluquer\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/iconproducts.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iconproducts.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/iconproducts.com\\\/es\\\/#organization\",\"name\":\"I.C.O.N. Products\",\"url\":\"https:\\\/\\\/iconproducts.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/iconproducts.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/iconproducts.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo-icon-1.jpg\",\"contentUrl\":\"https:\\\/\\\/iconproducts.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo-icon-1.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"I.C.O.N. Products\"},\"image\":{\"@id\":\"https:\\\/\\\/iconproducts.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/iconproducts.spain\",\"https:\\\/\\\/www.instagram.com\\\/iconspain\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCw0myea3fiZRsj72sNBnMqQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"India Cleansing Shampoo | I.C.O.N. Products","description":"India Cleansing de ICON, champ\u00fa limpiador y nutritivo para todo tipo de cabellos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iconproducts.com\/es\/icon-india\/india-cleansing-shampoo\/","og_locale":"es_ES","og_type":"article","og_title":"India Cleansing Shampoo | I.C.O.N. Products","og_description":"India Cleansing de ICON, champ\u00fa limpiador y nutritivo para todo tipo de cabellos.","og_url":"https:\/\/iconproducts.com\/es\/icon-india\/india-cleansing-shampoo\/","og_site_name":"I.C.O.N. Products","article_publisher":"https:\/\/www.facebook.com\/iconproducts.spain","article_modified_time":"2025-06-12T07:39:49+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/iconproducts.com\/es\/icon-india\/india-cleansing-shampoo\/","url":"https:\/\/iconproducts.com\/es\/icon-india\/india-cleansing-shampoo\/","name":"India Cleansing Shampoo | I.C.O.N. Products","isPartOf":{"@id":"https:\/\/iconproducts.com\/es\/#website"},"datePublished":"2023-07-13T10:06:31+00:00","dateModified":"2025-06-12T07:39:49+00:00","description":"India Cleansing de ICON, champ\u00fa limpiador y nutritivo para todo tipo de cabellos.","breadcrumb":{"@id":"https:\/\/iconproducts.com\/es\/icon-india\/india-cleansing-shampoo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iconproducts.com\/es\/icon-india\/india-cleansing-shampoo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/iconproducts.com\/es\/icon-india\/india-cleansing-shampoo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"I.C.O.N. Products","item":"https:\/\/iconproducts.com\/es\/"},{"@type":"ListItem","position":2,"name":"India","item":"https:\/\/iconproducts.com\/es\/icon-india\/"},{"@type":"ListItem","position":3,"name":"India Cleansing Shampoo"}]},{"@type":"WebSite","@id":"https:\/\/iconproducts.com\/es\/#website","url":"https:\/\/iconproducts.com\/es\/","name":"I.C.O.N. Products","description":"Productos de peluquer\u00eda","publisher":{"@id":"https:\/\/iconproducts.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iconproducts.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/iconproducts.com\/es\/#organization","name":"I.C.O.N. Products","url":"https:\/\/iconproducts.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/iconproducts.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/iconproducts.com\/wp-content\/uploads\/2018\/08\/logo-icon-1.jpg","contentUrl":"https:\/\/iconproducts.com\/wp-content\/uploads\/2018\/08\/logo-icon-1.jpg","width":1000,"height":1000,"caption":"I.C.O.N. Products"},"image":{"@id":"https:\/\/iconproducts.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/iconproducts.spain","https:\/\/www.instagram.com\/iconspain\/","https:\/\/www.youtube.com\/channel\/UCw0myea3fiZRsj72sNBnMqQ"]}]}},"_links":{"self":[{"href":"https:\/\/iconproducts.com\/es\/wp-json\/wp\/v2\/pages\/114328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iconproducts.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iconproducts.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iconproducts.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iconproducts.com\/es\/wp-json\/wp\/v2\/comments?post=114328"}],"version-history":[{"count":12,"href":"https:\/\/iconproducts.com\/es\/wp-json\/wp\/v2\/pages\/114328\/revisions"}],"predecessor-version":[{"id":124473,"href":"https:\/\/iconproducts.com\/es\/wp-json\/wp\/v2\/pages\/114328\/revisions\/124473"}],"up":[{"embeddable":true,"href":"https:\/\/iconproducts.com\/es\/wp-json\/wp\/v2\/pages\/19977"}],"wp:attachment":[{"href":"https:\/\/iconproducts.com\/es\/wp-json\/wp\/v2\/media?parent=114328"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iconproducts.com\/es\/wp-json\/wp\/v2\/tags?post=114328"},{"taxonomy":"wf_page_folders","embeddable":true,"href":"https:\/\/iconproducts.com\/es\/wp-json\/wp\/v2\/wf_page_folders?post=114328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}